{"id":20,"date":"2026-09-01T09:29:19","date_gmt":"2026-09-01T14:29:19","guid":{"rendered":"https:\/\/kaytutejidos.mypesdigitales.com\/index.php\/libro-de-reclamaciones\/"},"modified":"2026-09-01T09:29:19","modified_gmt":"2026-09-01T14:29:19","slug":"libro-de-reclamaciones","status":"publish","type":"page","link":"https:\/\/kaytutejidos.mypesdigitales.com\/index.php\/libro-de-reclamaciones\/","title":{"rendered":"Libro de Reclamaciones"},"content":{"rendered":"<h2>Lamentamos lo sucedido<\/h2>\n<p>Este es el Libro de Reclamaciones Virtual. En el podra poner de manifiesto alguna queja o reclamo respecto al descontento por el servicio. Le atenderemos en la brevedad. Los campos que se presentan son obligatorios para poder realizar su reclamo.<\/p>\n<ul>\n<li>Todos nuestros procedimientos estan basados en el manual de proteccion del consumidor y el manual de uso del libro de reclamaciones.<\/li>\n<li>La respuesta a este reclamo o queja sera enviada al e-mail indicado en este formulario.<\/li>\n<\/ul>\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f78-o1\" lang=\"\" dir=\"ltr\" data-wpcf7-id=\"78\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/index.php\/wp-json\/wp\/v2\/pages\/20#wpcf7-f78-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"78\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f78-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n\n<div class=\"form_libro_reclamaciones\">\n\n    <h3>1. Datos del consumidor<\/h3>\n\n    <div class=\"form_row\">\n        <div class=\"form_col\">\n            <label>Nombres<\/label>\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"consumidor_nombres\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Ingrese sus nombres\" value=\"\" type=\"text\" name=\"consumidor_nombres\" \/><\/span>\n        <\/div>\n    <\/div>\n\n    <div class=\"form_row\">\n        <div class=\"form_col\">\n            <label>Apellidos<\/label>\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"consumidor_apellidos\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Ingrese sus apellidos\" value=\"\" type=\"text\" name=\"consumidor_apellidos\" \/><\/span>\n        <\/div>\n    <\/div>\n\n    <div class=\"form_row\">\n        <div class=\"form_col\">\n            <label>Tipo de documento<\/label>\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"consumidor_documento\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"consumidor_documento\"><option value=\"DNI\">DNI<\/option><option value=\"CE\">CE<\/option><option value=\"Pasaporte\">Pasaporte<\/option><\/select><\/span>\n        <\/div>\n    <\/div>\n\n    <div class=\"form_row\">\n        <div class=\"form_col\">\n            <label>Numero de documento<\/label>\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"consumidor_numero_documento\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Ingrese su numero de documento\" value=\"\" type=\"text\" name=\"consumidor_numero_documento\" \/><\/span>\n        <\/div>\n    <\/div>\n\n    <div class=\"form_row\">\n        <div class=\"form_col\">\n            <label>Telefono \/ WhatsApp<\/label>\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"consumidor_telefono\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Ingrese su telefono o WhatsApp\" value=\"\" type=\"tel\" name=\"consumidor_telefono\" \/><\/span>\n        <\/div>\n    <\/div>\n\n    <div class=\"form_row\">\n        <div class=\"form_col\">\n            <label>Correo electronico<\/label>\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"consumidor_email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Ingrese su correo electronico\" value=\"\" type=\"email\" name=\"consumidor_email\" \/><\/span>\n        <\/div>\n    <\/div>\n\n    <div class=\"form_row\">\n        <div class=\"form_col\">\n            <label>Direccion<\/label>\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"consumidor_direccion\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Ingrese su direccion\" value=\"\" type=\"text\" name=\"consumidor_direccion\" \/><\/span>\n        <\/div>\n    <\/div>\n\n    <h3>2. Datos del reclamo<\/h3>\n\n    <div class=\"form_row\">\n        <div class=\"form_col\">\n            <label>Tipo de solicitud<\/label>\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"tipo_solicitud\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"tipo_solicitud\"><option value=\"Reclamo\">Reclamo<\/option><option value=\"Queja\">Queja<\/option><\/select><\/span>\n        <\/div>\n    <\/div>\n\n    <div class=\"form_row\">\n        <div class=\"form_col\">\n            <label>Servicio o producto contratado<\/label>\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"servicio_producto\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Ingrese el servicio o producto contratado\" value=\"\" type=\"text\" name=\"servicio_producto\" \/><\/span>\n        <\/div>\n    <\/div>\n\n    <div class=\"form_row\">\n        <div class=\"form_col\">\n            <label>Fecha del incidente<\/label>\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"fecha_incidente\"><input class=\"wpcf7-form-control wpcf7-date wpcf7-validates-as-date\" aria-invalid=\"false\" value=\"\" type=\"date\" name=\"fecha_incidente\" \/><\/span>\n        <\/div>\n    <\/div>\n\n    <div class=\"form_row\">\n        <div class=\"form_col\">\n            <label>Detalle del reclamo o queja<\/label>\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"detalle_reclamo\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Describa el detalle del reclamo o queja\" name=\"detalle_reclamo\"><\/textarea><\/span>\n        <\/div>\n    <\/div>\n\n    <div class=\"form_row\">\n        <div class=\"form_col\">\n            <label>Pedido del consumidor<\/label>\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"pedido_consumidor\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Indique su pedido o solucion solicitada\" name=\"pedido_consumidor\"><\/textarea><\/span>\n        <\/div>\n    <\/div>\n\n    <h3>3. Confirmacion<\/h3>\n\n    <div class=\"form_row\">\n        <div class=\"form_col\">\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"aceptacion\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"aceptacion\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">Declaro que la informacion registrada es verdadera y acepto el tratamiento de mis datos personales para la atencion del presente reclamo.<\/span><\/label><\/span><\/span><\/span>\n        <\/div>\n    <\/div>\n\n    <div class=\"form_submit\">\n        <input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"ENVIAR RECLAMO\" \/>\n    <\/div>\n\n    <div class=\"note_form_reclamaciones\">\n        <p><strong>Queja:<\/strong> Disconformidad no relacionada a los productos o servicios, o malestar o descontento con respecto a la atencion al publico.<\/p>\n        <p><strong>Reclamo:<\/strong> Disconformidad relacionada a los productos o servicios.<\/p>\n    <\/div>\n\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Lamentamos lo sucedido Este es el Libro de Reclamaciones Virtual. En el podra poner de manifiesto alguna queja o reclamo respecto al descontento por el servicio. Le atenderemos en la brevedad. Los campos que se presentan son obligatorios para poder realizar su reclamo. Todos nuestros procedimientos estan basados en el manual de proteccion del consumidor [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page_libro_reclamaciones.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-20","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/kaytutejidos.mypesdigitales.com\/index.php\/wp-json\/wp\/v2\/pages\/20","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kaytutejidos.mypesdigitales.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kaytutejidos.mypesdigitales.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kaytutejidos.mypesdigitales.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kaytutejidos.mypesdigitales.com\/index.php\/wp-json\/wp\/v2\/comments?post=20"}],"version-history":[{"count":0,"href":"https:\/\/kaytutejidos.mypesdigitales.com\/index.php\/wp-json\/wp\/v2\/pages\/20\/revisions"}],"wp:attachment":[{"href":"https:\/\/kaytutejidos.mypesdigitales.com\/index.php\/wp-json\/wp\/v2\/media?parent=20"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}